{"id":68769,"date":"2025-10-03T08:19:34","date_gmt":"2025-10-03T04:19:34","guid":{"rendered":"https:\/\/www.eliteprofessionaluae.com\/product\/%d9%83%d8%b1%d9%8a%d9%85-%d8%a3%d8%b3%d8%a7%d8%b3-%d8%a7%d9%84%d9%88%d8%ac%d9%87-%d8%b3%d9%8a%d9%86%d9%85%d8%a7-%d9%81%d9%8a%d9%84%d9%85-%d9%81%d9%8a%d9%84%d9%85-30-%d9%85%d9%84-9-%d8%a3%d9%84%d9%88\/"},"modified":"2025-10-03T08:21:12","modified_gmt":"2025-10-03T04:21:12","slug":"%d9%83%d8%b1%d9%8a%d9%85-%d8%a3%d8%b3%d8%a7%d8%b3-%d8%a7%d9%84%d9%88%d8%ac%d9%87-%d8%b3%d9%8a%d9%86%d9%85%d8%a7-%d9%81%d9%8a%d9%84%d9%85-%d9%81%d9%8a%d9%84%d9%85-30-%d9%85%d9%84-9-%d8%a3%d9%84%d9%88","status":"publish","type":"product","link":"https:\/\/www.eliteprofessionaluae.com\/ar\/product\/%d9%83%d8%b1%d9%8a%d9%85-%d8%a3%d8%b3%d8%a7%d8%b3-%d8%a7%d9%84%d9%88%d8%ac%d9%87-%d8%b3%d9%8a%d9%86%d9%85%d8%a7-%d9%81%d9%8a%d9%84%d9%85-%d9%81%d9%8a%d9%84%d9%85-30-%d9%85%d9%84-9-%d8%a3%d9%84%d9%88\/","title":{"rendered":"\u0643\u0631\u064a\u0645 \u0623\u0633\u0627\u0633 \u0627\u0644\u0648\u062c\u0647 \u0633\u064a\u0646\u0645\u0627-\u0641\u064a\u0644\u0645 \u0641\u064a\u0644\u0645 30 \u0645\u0644 (9 \u0623\u0644\u0648\u0627\u0646 \u0645\u062e\u062a\u0644\u0641\u0629)"},"content":{"rendered":"<p>\u2022 \u0627\u0644\u0623\u0633\u0627\u0633 \u0627\u0644\u0633\u0627\u0626\u0644 \u0627\u0644\u0645\u0627\u0626\u064a \u0627\u0644\u0646\u0647\u0627\u0626\u064a! \u0645\u0645\u062a\u0627\u0632 \u0644\u062c\u0645\u064a\u0639 \u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0628\u0634\u0631\u0629.<\/p>\n<p>\u2022 \u0645\u064a\u0632\u0629 Feature Film Foundation \u0645\u062a\u0645\u064a\u0632\u0629 \u0641\u064a \u062a\u0648\u0641\u064a\u0631 \u0645\u0638\u0647\u0631 \u0644\u0637\u064a\u0641 \u0648\u0633\u0644\u0633 \u0648\u0645\u0648\u062d\u062f \u0645\u0639 \u062a\u0648\u0641\u064a\u0631 \u062a\u063a\u0637\u064a\u0629 \u0625\u0636\u0627\u0641\u064a\u0629 \u0644\u0644\u0648\u062c\u0647.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 \u0627\u0644\u0623\u0633\u0627\u0633 \u0627\u0644\u0633\u0627\u0626\u0644 \u0627\u0644\u0645\u0627\u0626\u064a \u0627\u0644\u0646\u0647\u0627\u0626\u064a! \u0645\u0645\u062a\u0627\u0632 \u0644\u062c\u0645\u064a\u0639 \u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0628\u0634\u0631\u0629. \u2022 \u0645\u064a\u0632\u0629 Feature Film Foundation \u0645\u062a\u0645\u064a\u0632\u0629 \u0641\u064a \u062a\u0648\u0641\u064a\u0631 \u0645\u0638\u0647\u0631 \u0644\u0637\u064a\u0641 \u0648\u0633\u0644\u0633 \u0648\u0645\u0648\u062d\u062f \u0645\u0639 \u062a\u0648\u0641\u064a\u0631 \u062a\u063a\u0637\u064a\u0629 \u0625\u0636\u0627\u0641\u064a\u0629 \u0644\u0644\u0648\u062c\u0647.<\/p>\n","protected":false},"featured_media":68735,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[409],"product_cat":[354],"product_tag":[],"class_list":["post-68769","product","type-product","status-publish","has-post-thumbnail","product_brand-cinema-ar","product_cat-354","first","instock","shipping-taxable","purchasable","product-type-variable","wvs-archive-product-wrapper"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.eliteprofessionaluae.com\/ar\/wp-json\/wp\/v2\/product\/68769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eliteprofessionaluae.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.eliteprofessionaluae.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eliteprofessionaluae.com\/ar\/wp-json\/wp\/v2\/comments?post=68769"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eliteprofessionaluae.com\/ar\/wp-json\/wp\/v2\/media\/68735"}],"wp:attachment":[{"href":"https:\/\/www.eliteprofessionaluae.com\/ar\/wp-json\/wp\/v2\/media?parent=68769"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.eliteprofessionaluae.com\/ar\/wp-json\/wp\/v2\/product_brand?post=68769"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.eliteprofessionaluae.com\/ar\/wp-json\/wp\/v2\/product_cat?post=68769"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.eliteprofessionaluae.com\/ar\/wp-json\/wp\/v2\/product_tag?post=68769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}