{"id":60837,"date":"2025-10-02T21:26:47","date_gmt":"2025-10-02T17:26:47","guid":{"rendered":"https:\/\/www.eliteprofessionaluae.com\/product\/%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d8%ad%d8%b1%d8%a7%d8%b1%d9%8a%d8%a9-%d9%85%d8%b9-%d8%a3%d9%86%d8%a8%d9%88%d8%a8-%d9%85%d9%86-%d8%a7%d9%84%d8%a3%d9%84%d9%88%d9%85%d9%86%d9%8a%d9%88%d9%85-2\/"},"modified":"2025-10-02T21:27:45","modified_gmt":"2025-10-02T17:27:45","slug":"%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d8%ad%d8%b1%d8%a7%d8%b1%d9%8a%d8%a9-%d9%85%d8%b9-%d8%a3%d9%86%d8%a8%d9%88%d8%a8-%d9%85%d9%86-%d8%a7%d9%84%d8%a3%d9%84%d9%88%d9%85%d9%86%d9%8a%d9%88%d9%85-2","status":"publish","type":"product","link":"https:\/\/www.eliteprofessionaluae.com\/ar\/product\/%d9%81%d8%b1%d8%b4%d8%a7%d8%a9-%d8%ad%d8%b1%d8%a7%d8%b1%d9%8a%d8%a9-%d9%85%d8%b9-%d8%a3%d9%86%d8%a8%d9%88%d8%a8-%d9%85%d9%86-%d8%a7%d9%84%d8%a3%d9%84%d9%88%d9%85%d9%86%d9%8a%d9%88%d9%85-2\/","title":{"rendered":"\u0641\u0631\u0634\u0627\u0629 \u062d\u0631\u0627\u0631\u064a\u0629 \u0645\u0639 \u0623\u0646\u0628\u0648\u0628  \u0645\u0646 \u0627\u0644\u0623\u0644\u0648\u0645\u0646\u064a\u0648\u0645"},"content":{"rendered":"<p> \u0646\u0627\u064a\u0644\u0648\u0646 \u0627\u062d\u062a\u0631\u0627\u0641\u064a \u0645\u0642\u0627\u0648\u0645 \u0644\u0644\u062d\u0631\u0627\u0631\u0629 \u060c&nbsp;\u0628\u0645\u0642\u0628\u0636 \u062e\u0634\u0628\u064a \u0645\u0646 \u062e\u0634\u0628 \u0627\u0644\u062f\u0631\u062f\u0627\u0631 \u0645\u0639 \u0648\u062c\u0648\u062f \u062e\u0627\u0635\u064a\u0629 \u062a\u0642\u0633\u064a\u0645 \u0627\u0644\u0634\u0639\u0631<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0646\u0627\u064a\u0644\u0648\u0646 \u0627\u062d\u062a\u0631\u0627\u0641\u064a \u0645\u0642\u0627\u0648\u0645 \u0644\u0644\u062d\u0631\u0627\u0631\u0629 \u060c&nbsp;\u0628\u0645\u0642\u0628\u0636 \u062e\u0634\u0628\u064a \u0645\u0646 \u062e\u0634\u0628 \u0627\u0644\u062f\u0631\u062f\u0627\u0631 \u0645\u0639 \u0648\u062c\u0648\u062f \u062e\u0627\u0635\u064a\u0629 \u062a\u0642\u0633\u064a\u0645 \u0627\u0644\u0634\u0639\u0631<\/p>\n","protected":false},"featured_media":60813,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[407],"product_cat":[328],"product_tag":[],"class_list":["post-60837","product","type-product","status-publish","has-post-thumbnail","product_brand-3me-maestri-ar","product_cat--3me","first","instock","shipping-taxable","purchasable","product-type-variable","wvs-archive-product-wrapper"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.eliteprofessionaluae.com\/ar\/wp-json\/wp\/v2\/product\/60837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eliteprofessionaluae.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.eliteprofessionaluae.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eliteprofessionaluae.com\/ar\/wp-json\/wp\/v2\/comments?post=60837"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eliteprofessionaluae.com\/ar\/wp-json\/wp\/v2\/media\/60813"}],"wp:attachment":[{"href":"https:\/\/www.eliteprofessionaluae.com\/ar\/wp-json\/wp\/v2\/media?parent=60837"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.eliteprofessionaluae.com\/ar\/wp-json\/wp\/v2\/product_brand?post=60837"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.eliteprofessionaluae.com\/ar\/wp-json\/wp\/v2\/product_cat?post=60837"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.eliteprofessionaluae.com\/ar\/wp-json\/wp\/v2\/product_tag?post=60837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}